{"id":5652,"date":"2016-03-10T14:22:18","date_gmt":"2016-03-10T14:22:18","guid":{"rendered":"http:\/\/ossmozambique.com\/?page_id=5652&#038;lang=pt-pt"},"modified":"2016-03-30T18:39:35","modified_gmt":"2016-03-30T18:39:35","slug":"imoveis","status":"publish","type":"page","link":"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/","title":{"rendered":"Im\u00f3veis"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5652","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Im\u00f3veis e Espa\u00e7os de Armazenamento | Servi\u00e7os de Armazenamento em Mo\u00e7ambique<\/title>\n<meta name=\"description\" content=\"Na OSS Mozambique encontrar\u00e1 unidades e espa\u00e7os de armazenamento de confian\u00e7a, adequados a todas as suas atividades industriais. Os nossos im\u00f3veis compreendem dimens\u00f5es entre 300 m2 a 600 m2 e podem ser adaptados aos requisitos dos nossos clientes. Garantimos ainda servi\u00e7os de seguran\u00e7a 24 horas por dia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im\u00f3veis e Espa\u00e7os de Armazenamento | Servi\u00e7os de Armazenamento em Mo\u00e7ambique\" \/>\n<meta property=\"og:description\" content=\"Na OSS Mozambique encontrar\u00e1 unidades e espa\u00e7os de armazenamento de confian\u00e7a, adequados a todas as suas atividades industriais. Os nossos im\u00f3veis compreendem dimens\u00f5es entre 300 m2 a 600 m2 e podem ser adaptados aos requisitos dos nossos clientes. Garantimos ainda servi\u00e7os de seguran\u00e7a 24 horas por dia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/\" \/>\n<meta property=\"og:site_name\" content=\"Warehousing Solutions &amp; Storage Services in Mozambique\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-30T18:39:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ossmozambique.com\\\/pt-pt\\\/imoveis\\\/\",\"url\":\"https:\\\/\\\/ossmozambique.com\\\/pt-pt\\\/imoveis\\\/\",\"name\":\"Im\u00f3veis e Espa\u00e7os de Armazenamento | Servi\u00e7os de Armazenamento em Mo\u00e7ambique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ossmozambique.com\\\/#website\"},\"datePublished\":\"2016-03-10T14:22:18+00:00\",\"dateModified\":\"2016-03-30T18:39:35+00:00\",\"description\":\"Na OSS Mozambique encontrar\u00e1 unidades e espa\u00e7os de armazenamento de confian\u00e7a, adequados a todas as suas atividades industriais. Os nossos im\u00f3veis compreendem dimens\u00f5es entre 300 m2 a 600 m2 e podem ser adaptados aos requisitos dos nossos clientes. Garantimos ainda servi\u00e7os de seguran\u00e7a 24 horas por dia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ossmozambique.com\\\/pt-pt\\\/imoveis\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ossmozambique.com\\\/pt-pt\\\/imoveis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ossmozambique.com\\\/pt-pt\\\/imoveis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ossmozambique.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im\u00f3veis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ossmozambique.com\\\/#website\",\"url\":\"https:\\\/\\\/ossmozambique.com\\\/\",\"name\":\"Warehousing Solutions &amp; Storage Services in Mozambique\",\"description\":false,\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ossmozambique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Im\u00f3veis e Espa\u00e7os de Armazenamento | Servi\u00e7os de Armazenamento em Mo\u00e7ambique","description":"Na OSS Mozambique encontrar\u00e1 unidades e espa\u00e7os de armazenamento de confian\u00e7a, adequados a todas as suas atividades industriais. Os nossos im\u00f3veis compreendem dimens\u00f5es entre 300 m2 a 600 m2 e podem ser adaptados aos requisitos dos nossos clientes. Garantimos ainda servi\u00e7os de seguran\u00e7a 24 horas por dia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/","og_locale":"pt_PT","og_type":"article","og_title":"Im\u00f3veis e Espa\u00e7os de Armazenamento | Servi\u00e7os de Armazenamento em Mo\u00e7ambique","og_description":"Na OSS Mozambique encontrar\u00e1 unidades e espa\u00e7os de armazenamento de confian\u00e7a, adequados a todas as suas atividades industriais. Os nossos im\u00f3veis compreendem dimens\u00f5es entre 300 m2 a 600 m2 e podem ser adaptados aos requisitos dos nossos clientes. Garantimos ainda servi\u00e7os de seguran\u00e7a 24 horas por dia.","og_url":"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/","og_site_name":"Warehousing Solutions &amp; Storage Services in Mozambique","article_modified_time":"2016-03-30T18:39:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/","url":"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/","name":"Im\u00f3veis e Espa\u00e7os de Armazenamento | Servi\u00e7os de Armazenamento em Mo\u00e7ambique","isPartOf":{"@id":"https:\/\/ossmozambique.com\/#website"},"datePublished":"2016-03-10T14:22:18+00:00","dateModified":"2016-03-30T18:39:35+00:00","description":"Na OSS Mozambique encontrar\u00e1 unidades e espa\u00e7os de armazenamento de confian\u00e7a, adequados a todas as suas atividades industriais. Os nossos im\u00f3veis compreendem dimens\u00f5es entre 300 m2 a 600 m2 e podem ser adaptados aos requisitos dos nossos clientes. Garantimos ainda servi\u00e7os de seguran\u00e7a 24 horas por dia.","breadcrumb":{"@id":"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ossmozambique.com\/pt-pt\/imoveis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ossmozambique.com\/pt-pt\/imoveis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ossmozambique.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Im\u00f3veis"}]},{"@type":"WebSite","@id":"https:\/\/ossmozambique.com\/#website","url":"https:\/\/ossmozambique.com\/","name":"Warehousing Solutions &amp; Storage Services in Mozambique","description":false,"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ossmozambique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/pages\/5652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=5652"}],"version-history":[{"count":7,"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/pages\/5652\/revisions"}],"predecessor-version":[{"id":5895,"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/pages\/5652\/revisions\/5895"}],"wp:attachment":[{"href":"https:\/\/ossmozambique.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=5652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}